{"id":7355,"date":"2017-04-07T15:59:59","date_gmt":"2017-04-07T13:59:59","guid":{"rendered":"https:\/\/winheller.com\/blog\/?p=7355"},"modified":"2022-02-18T15:45:18","modified_gmt":"2022-02-18T13:45:18","slug":"null-euro-steuerbescheid","status":"publish","type":"post","link":"https:\/\/winheller.com\/blog\/null-euro-steuerbescheid\/","title":{"rendered":"Muss man gegen einen Null-Euro-Steuerbescheid vorgehen?"},"content":{"rendered":"<p>Gelegentlich erlassen die Finanz\u00e4mter gegen\u00fcber gemeinn\u00fctzigen K\u00f6rperschaften sog. Null-Euro-Steuerbescheide. Das hei\u00dft, das Finanzamt setzt die Steuerschuld gegen die betroffene K\u00f6rperschaft in H\u00f6he von 0 Euro fest. Grund zur Freude ist dies meist nicht. Gemeinn\u00fctzige K\u00f6rperschaften, denen ein solcher Bescheid ins Haus flattert, sollten ihn unbedingt genauestens \u00fcberpr\u00fcfen. Denn wenn das Finanzamt eine Steuerzahllast von 0 Euro festsetzt, erkennt es im gleichen Atemzug die Eigenschaft als steuerbefreite Organisation ab. Mit anderen Worten: Das Finanzamt geht davon aus, dass die K\u00f6rperschaft grunds\u00e4tzlich steuerpflichtig ist (also nicht gemeinn\u00fctzig und damit steuerbefreit), dass aber aus sonstigen Gr\u00fcnden die Steuer nur 0 Euro betr\u00e4gt, z.B. weil sich die NPO nur \u00fcber Mitgliedsbeitr\u00e4ge oder Spenden finanziert, die stets steuerfrei vereinnahmt werden k\u00f6nnen.<\/p>\n<h3>NPOs k\u00f6nnen sich wehren<\/h3>\n<p>Fr\u00fcher war zwar umstritten, ob sich eine <a href=\"https:\/\/www.winheller.com\/gemeinnuetzigkeitsrecht.html\" target=\"_blank\" rel=\"noopener\"><strong>gemeinn\u00fctzige K\u00f6rperschaft<\/strong><\/a> gegen einen Null-Euro-Steuerbescheid zur Wehr setzen kann, denn schlie\u00dflich hat die K\u00f6rperschaft auch mit einem Null-Euro-Steuerbescheid keine Steuer zu zahlen. Der Bundesfinanzhof (BFH) hat aber bereits im Jahr 1994 die M\u00f6glichkeit der gerichtlichen \u00dcberpr\u00fcfung eines solchen Bescheides anerkannt und seine Rechtsprechung erst k\u00fcrzlich mit Urteil vom 22.06.2016, Az. V R 49\/15 wieder best\u00e4tigt. Ist die K\u00f6rperschaft gemeinn\u00fctzig, muss sie also einen Null-Euro-Steuerbescheid nicht akzeptieren. Sie kann stattdessen einen sog. Freistellungsbescheid verlangen oder Anlagen zu ihrem Steuerbescheid, die sie in Bezug auf ihre Bet\u00e4tigungen au\u00dferhalb eines steuerpflichtigen wirtschaftlichen Gesch\u00e4ftsbetriebs von der Steuer befreien.<\/p>\n<h3>Herbe Konsequenzen beim Verlust der Gemeinn\u00fctzigkeit<\/h3>\n<p>Wenn eine K\u00f6rperschaft \u00fcbersieht, dass ihr mit dem Null-Euro-Steuerbescheid die <a href=\"https:\/\/www.winheller.com\/gemeinnuetzigkeitsrecht\/aberkennung-gemeinnuetzigkeit.html\" target=\"_blank\" rel=\"noopener\"><strong>Gemeinn\u00fctzigkeit aberkannt<\/strong><\/a> wurde, und die kurze einmonatige Einspruchsfrist verstreichen l\u00e4sst, wird der Steuerbescheid bestandskr\u00e4ftig. Eine Korrektur ist dann nicht mehr m\u00f6glich. Die Gemeinn\u00fctzigkeit ist dann tats\u00e4chlich aberkannt. Die K\u00f6rperschaft darf dann vor allem keine Spendenbescheinigungen mehr ausstellen. Macht sie das gleichwohl, haftet sie in H\u00f6he von 30 Prozent der ausgewiesenen Spendenbescheinigungssumme (sog. Spendenhaftung). Mit dem Status als gemeinn\u00fctzige K\u00f6rperschaft sind daneben auch Verwaltungsgeb\u00fchrenbefreiungen und sonstige Befreiungen, wie beispielsweise von Kontof\u00fchrungsgeb\u00fchren, verbunden. Nicht zuletzt erfolgt die Vergabe staatlicher F\u00f6rdermittel h\u00e4ufig nur an als gemeinn\u00fctzig anerkannte K\u00f6rperschaften. Es ist daher wichtig, dass die K\u00f6rperschaft f\u00fcr den Erhalt ihres Gemeinn\u00fctzigkeitsstatus k\u00e4mpft.<\/p>\n<p>Weiterlesen:<br \/>\n<a href=\"https:\/\/winheller.com\/blog\/entzug-der-gemeinnuetzigkeit-klage-nullbescheid\/\" target=\"_blank\" rel=\"noopener\"><strong>Entzug der Gemeinn\u00fctzigkeit: Klage gegen Nullbescheid nur bei tats\u00e4chlicher Beschwerde zul\u00e4ssig<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.winheller.com\/gemeinnuetzigkeitsrecht\/aberkennung-gemeinnuetzigkeit.html\" target=\"_blank\" rel=\"noopener\"><strong>Aberkennung der Gemeinn\u00fctzigkeit und Folgeprobleme<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gelegentlich erlassen die Finanz\u00e4mter gegen\u00fcber gemeinn\u00fctzigen K\u00f6rperschaften sog. Null-Euro-Steuerbescheide. Das hei\u00dft, das Finanzamt setzt die Steuerschuld gegen die betroffene K\u00f6rperschaft in H\u00f6he von 0 Euro fest. Grund zur Freude ist dies meist nicht. Gemeinn\u00fctzige K\u00f6rperschaften, denen ein solcher Bescheid ins Haus [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":9918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2129],"tags":[189,450],"class_list":["post-7355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basics","tag-finanzamt","tag-steuerbescheid"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/7355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/comments?post=7355"}],"version-history":[{"count":2,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/7355\/revisions"}],"predecessor-version":[{"id":9127,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/7355\/revisions\/9127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/media\/9918"}],"wp:attachment":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/media?parent=7355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/categories?post=7355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/tags?post=7355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}