{"id":6333,"date":"2016-08-03T09:40:01","date_gmt":"2016-08-03T07:40:01","guid":{"rendered":"https:\/\/winheller.com\/blog\/?p=6333"},"modified":"2018-01-04T11:29:46","modified_gmt":"2018-01-04T09:29:46","slug":"blockchain-zentralbanken","status":"publish","type":"post","link":"https:\/\/winheller.com\/blog\/blockchain-zentralbanken\/","title":{"rendered":"Bank of England bef\u00fcrwortet Blockchain der Zentralbanken"},"content":{"rendered":"<p>Der \u00d6konom James Tobin ver\u00f6ffentlichte bereits 1987 einen Aufsatz in dem er die Frage stellte, ob \u201eman <a href=\"https:\/\/www.winheller.com\/bankrecht-finanzrecht.html\" target=\"_blank\"><strong>gro\u00dfe Finanzinstitute<\/strong><\/a> scheitern lassen [darf]?\u201c. Heute, nach der gro\u00dfen Finanzkrise von 2008, kennen wir die Antwort. Tobin schlug damals vor, der Bev\u00f6lkerung direkten Zugriff auf Zentralbankkonten zu geben. Was vor drei\u00dfig Jahren schwer umzusetzen war, hat nun die Bank of England (BoE) in einem Forschungspapier aufgegriffen. Demnach k\u00f6nnte Tobins Vorschlag in greifbare N\u00e4he ger\u00fcckt sein \u2013 mit Hilfe der Blockchain.<\/p>\n<h3>Insolvenz einer Bank bedroht Erspartes der B\u00fcrger<\/h3>\n<p>Das Problem am modernen Finanzwesen ist, dass f\u00fcr den Verbraucher nur Bargeld eine insolvenzsichere Sparm\u00f6glichkeit bietet. Bargeld ist aber f\u00fcr regelm\u00e4\u00dfige Zahlungen wie \u00dcberweisung der Miete und f\u00fcr den digitalen Onlinehandel kaum geeignet. \u00dcblicherweise verwahrt man sein Erspartes deshalb bei einer Bank. Allerdings ist der Verbraucher nicht Eigent\u00fcmer des Geldes auf seinem Konto. Vielmehr repr\u00e4sentiert dieses nur eine Verbindlichkeit der Bank gegen\u00fcber ihrem Kunden. Schlittert die <a href=\"https:\/\/www.winheller.com\/bankrecht-finanzrecht\/bankrecht.html\" target=\"_blank\"><strong>Bank<\/strong><\/a> in die Insolvenz, ist die R\u00fcckzahlung des Ersparten gef\u00e4hrdet.<\/p>\n<p>Daher haben die meisten Staaten Einlagensicherungssysteme eingef\u00fchrt. Diese sollen Kontoinhabern die R\u00fcckzahlung des Ersparten bis zu einem bestimmten Limit garantieren. Allerdings k\u00f6nnen diese Versicherungen oft nur die Insolvenz kleinerer Institute auffangen. Ger\u00e4t hingegen eine gro\u00dfe Bank in Schieflage, bedroht dies aufgrund der hohen Vernetzung oft auch zahlreiche weitere Kreditinstitute. Daher erscheint es dem Staat g\u00fcnstiger, taumelnde Banken mit Steuergeldern zu st\u00fctzen, statt bei einem Einsturz die Scherben des Finanzsystems aufzukehren.<\/p>\n<h3>Bank of England schl\u00e4gt digitales Zentralbankgeld vor<\/h3>\n<p>Die BoE schl\u00e4gt deshalb vor, eine Blockchain der Zentralbanken einzuf\u00fchren. Auf dieser soll dann staatliches Fiatgeld, \u00e4quivalent zum Bargeld, gehandelt werden. Jedermann kann sich dann eine \u201eEurowallet\u201c installieren. Wer sein Geld auf dieser Wallet speichert, h\u00e4lt es direkt bei der Zentralbank und somit ohne Insolvenzrisiko.<\/p>\n<p>Dieses Geld ist im Gegensatz zu Bargeld genauso vielseitig einsetzbar wie das heutige <a href=\"https:\/\/www.winheller.com\/bankrecht-finanzrecht\/bitcointrading.html\" target=\"_blank\"><strong>elektronische Geld<\/strong><\/a>. Es k\u00f6nnen \u00dcberweisungen get\u00e4tigt und Dauerauftr\u00e4ge angelegt werden. Zahlungen k\u00f6nnen in beliebiger H\u00f6he und \u00fcber beliebige Entfernungen angesto\u00dfen werden. Und da eine Blockchain keine Gesch\u00e4ftszeiten kennt, funktioniert dies 24 Stunden am Tag inklusive Wochenenden und Feiertagen.<\/p>\n<h3>Blockchain bringt Sicherheit und f\u00f6rdert Innovation<\/h3>\n<p>Dadurch wird einer Krise im Finanzsektor der Schrecken genommen. Wenn Sparer ihr Geld insolvenzsicher anlegen k\u00f6nnen, ist es ihre freie Entscheidung, es einer kommerziellen Bank anzuvertrauen. Hierdurch k\u00f6nnten sie z.B. durch h\u00f6here Zinsen veranlasst werden. Die Insolvenz einer Bank k\u00f6nnte fortan wie die Insolvenz jedes sonstigen Unternehmens behandelt werden.<\/p>\n<p>Dies erm\u00f6glicht es auch, die Regulierung des Bankensektors herunterzufahren. Seit 2008 wurde hier eine un\u00fcbersehbare Anzahl neuer Regeln erlassen und eine byzantinisch anmutende B\u00fcrokratie von Aufsichtsbeh\u00f6rden geschaffen. Diese Regeln, die eine Bankeninsolvenz verhindern sollen, erschweren gleichzeitig neuen Firmen den Markteintritt.<\/p>\n<p>Wenn Sie bereits heute die Blockchain f\u00fcr innovative Gesch\u00e4ftsmodelle nutzen wollen, navigieren Sie unsere auf Bank- und Kapitalmarktrecht spezialisierten Anw\u00e4lte gerne durch das Meer der Vorschriften und stehen Ihnen mit Rat und Tat zur Seite.<\/p>\n<p>Weiterlesen:<br \/>\n<a href=\"zentralbanken-einsatz-digitaler-waehrungen\/\" target=\"_blank\"><strong>Zentralbanken erw\u00e4gen Einsatz digitaler W\u00e4hrungen<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.winheller.com\/bankrecht-finanzrecht\/bankrecht.html\" target=\"_blank\"><strong>Full-Service Betreuung von Banken und Finanzdienstleistern<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der \u00d6konom James Tobin ver\u00f6ffentlichte bereits 1987 einen Aufsatz in dem er die Frage stellte, ob \u201eman gro\u00dfe Finanzinstitute scheitern lassen [darf]?\u201c. Heute, nach der gro\u00dfen Finanzkrise von 2008, kennen wir die Antwort. Tobin schlug damals vor, der Bev\u00f6lkerung direkten Zugriff [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":8142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[647],"tags":[],"class_list":["post-6333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/6333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/comments?post=6333"}],"version-history":[{"count":3,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/6333\/revisions"}],"predecessor-version":[{"id":8338,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/6333\/revisions\/8338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/media\/8142"}],"wp:attachment":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/media?parent=6333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/categories?post=6333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/tags?post=6333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}