{"id":16220,"date":"2022-03-30T12:35:59","date_gmt":"2022-03-30T10:35:59","guid":{"rendered":"https:\/\/winheller.com\/blog\/?p=16220"},"modified":"2022-03-30T12:36:01","modified_gmt":"2022-03-30T10:36:01","slug":"satzungsgestaltung-regelungen-vermoegensbindung","status":"publish","type":"post","link":"https:\/\/winheller.com\/blog\/satzungsgestaltung-regelungen-vermoegensbindung\/","title":{"rendered":"Satzungsgestaltung: Regelungen zur Verm\u00f6gensbindung exakt formulieren"},"content":{"rendered":"\n<div class=\"wp-block-image is-style-rounded wp-duotone-263388-ffffff-1\"><figure class=\"alignright size-full\"><a href=\"https:\/\/winheller.com\/blog\/wp-content\/uploads\/2022\/03\/satzungsgestaltung-regelungen-vermoegensbindung.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/winheller.com\/blog\/wp-content\/uploads\/2022\/03\/satzungsgestaltung-regelungen-vermoegensbindung.webp\" alt=\"Satzungsgestaltung: Regelungen zur Verm\u00f6gensbindung exakt formulieren\" class=\"wp-image-16244\" srcset=\"https:\/\/winheller.com\/blog\/wp-content\/uploads\/2022\/03\/satzungsgestaltung-regelungen-vermoegensbindung.webp 400w, https:\/\/winheller.com\/blog\/wp-content\/uploads\/2022\/03\/satzungsgestaltung-regelungen-vermoegensbindung-300x200.webp 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-drop-cap\">Die Satzung ist das Herzst\u00fcck einer gemeinn\u00fctzigen Organisation. \u00dcber ihre Gestaltung kann so mancher Streit innerhalb der eigenen Reihen, aber auch mit den Beh\u00f6rden wie zum Beispiel dem Finanzamt entstehen. Wie wichtig eine gute Satzungsgestaltung ist, zeigt j\u00fcngst ein Urteil des Bundesfinanzhofs (BFH).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Streit um Satzung mit dem Finanzamt<\/h2>\n\n\n\n<p>Die Kl\u00e4gerin ist eine <strong>GmbH<\/strong>, deren <strong>Satzungszweck<\/strong> die <strong>gemeindepsychiatrische Versorgung eines Landkreises<\/strong> ist. Nachdem das Finanzamt der Kl\u00e4gerin bereits 2014 mitteilte, dass ihr Gesellschaftsvertrag (Satzung) nicht den gemeinn\u00fctzigkeitsrechtlichen Voraussetzungen entspreche und sie bat, die gemeinn\u00fctzigen Zwecke gem\u00e4\u00df \u00a7 52 Abs. 2 der Abgabenordnung (AO) analog der Mustersatzung wortw\u00f6rtlich in ihrer <strong><a href=\"https:\/\/www.winheller.com\/gemeinnuetzigkeitsrecht\/satzungsgestaltung.html\" target=\"_blank\" rel=\"noreferrer noopener\">Satzung<\/a><\/strong> zu benennen, beschlossen die Gesellschafter der GmbH 2015 eine Satzungs\u00e4nderung.&nbsp;<\/p>\n\n\n\n<p>Jedoch beanstandete das Finanzamt die <strong><a href=\"https:\/\/winheller.com\/blog\/gemeinnuetzigkeit-servicegesellschaften-satzungsaenderung\/\" target=\"_blank\" rel=\"noreferrer noopener\">Satzungs\u00e4nderung<\/a><\/strong> und schlug der GmbH die Aufnahme der Zwecke \u201eF\u00f6rderung des \u00f6ffentlichen Gesundheitswesens und der \u00f6ffentlichen Gesundheitspflege\u201c sowie \u201eF\u00f6rderung mildt\u00e4tiger Zwecke\u201c in die Satzung vor. Zudem schlug es vor, auch die Regelung zur Aufl\u00f6sung der Gesellschaft an die Mustersatzung anzupassen. Zwar enthielt der Gesellschaftsvertrag eine Regelung zur Verm\u00f6gensbindung im Fall einer Aufl\u00f6sung der GmbH, jedoch nicht f\u00fcr den Fall, dass der bisherige Zweck der GmbH wegfallen w\u00fcrde.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Finanzamt lehnt Erteilung eines Feststellungsbescheids ab<\/h2>\n\n\n\n<p>Ende des Jahres 2016 lehnte das Finanzamt die Erteilung eines Feststellungsbescheides gem\u00e4\u00df \u00a7 60a AO ab, da die Satzung der GmbH die satzungsm\u00e4\u00dfigen Voraussetzungen nach den \u00a7\u00a7&nbsp;51, 59, 60 und 61 AO nicht erf\u00fclle. Dagegen reichte die GmbH Klage vor dem hessischen Finanzgericht (FG) ein.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.winheller.com\/news\/newsletter\/nonprofitrecht-aktuell-npr.html\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00f6chten Sie Neuigkeiten wie diese monatlich in Ihr Postfach erhalten? Abonnieren Sie hier unseren Newsletter Nonprofitrecht aktuell.<\/a><\/h4>\n\n\n\n<p>Mit Erfolg:&nbsp;<strong><a href=\"https:\/\/winheller.com\/blog\/mustersatzung-wortlaut-verbindlich\/\" target=\"_blank\" rel=\"noreferrer noopener\">Das Gericht entschied<\/a><\/strong>, dass die in \u00a7 52 Abs. 2 AO genannten Zwecke in der Satzung <strong>nicht wortw\u00f6rtlich wiederholt<\/strong> werden m\u00fcssten. Zudem gen\u00fcge der Gesellschaftsvertrag der GmbH auch ohne eine Regelung zur Verm\u00f6gensbindung bei einem Wegfall ihres bisherigen Zweckes den Anforderungen an die satzungsm\u00e4\u00dfige Verm\u00f6gensbindung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verm\u00f6gensbindung muss konkret in Satzung geregelt werden<\/h2>\n\n\n\n<p>Der BFH teilte jedoch die Ansicht des FG zur satzungsm\u00e4\u00dfigen Verm\u00f6gensbindung nicht und hob dessen Entscheidung auf. Eine <strong>steuerlich ausreichende Verm\u00f6gensbindung <\/strong>nach \u00a7 61 Abs. 1 AO liege, so der BFH, nur dann vor, wenn bei&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Aufl\u00f6sung der NPO,<\/li><li>Aufhebung der NPO und<\/li><li>Wegfall des bisherigen Zwecks der NPO&nbsp;<\/li><\/ul>\n\n\n\n<p>der Zweck, f\u00fcr den das anfallende Verm\u00f6gen verwendet werden soll, in der Satzung so genau bestimmt sei, dass allein anhand der Satzung gepr\u00fcft werden k\u00f6nne, ob der Verwendungszweck steuerbeg\u00fcnstigt ist.&nbsp;<\/p>\n\n\n\n<p>Es reiche nicht aus, nur den Verwendungszweck f\u00fcr einen oder zwei der m\u00f6glichen Verm\u00f6gensanfallsgr\u00fcnde in der Satzung zu nennen und diesen mittels Auslegung der Satzung auch f\u00fcr den\/die anderen anzunehmen. Zur Auslegung k\u00f6nne auch nicht wie vom FG angenommen die vorherige Handhabung der Beteiligten herangezogen werden, da die Regelungen \u00fcber die Verm\u00f6gensbindung in der Satzung selbst geregelt werden m\u00fcssten und sich nicht aus den Begleitumst\u00e4nden ergeben k\u00f6nnten.<\/p>\n\n\n\n<p>Da die Satzung der GmbH bereits die Anforderungen an die satzungsm\u00e4\u00dfige Verm\u00f6gensbindung gem\u00e4\u00df \u00a7 61 Abs. 1 AO nicht erf\u00fclle, m\u00fcsse die Frage, ob die in \u00a7 52 Abs. 2 AO genannten Zwecke in die Satzung w\u00f6rtlich \u00fcbernommen werden m\u00fcssen, nicht entschieden werden, so der BFH.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Besser an Mustersatzung orientieren<\/h2>\n\n\n\n<p>Es handelt sich hierbei um einen <strong>offensichtlichen Extremfall<\/strong>: Trotz mehrmaliger Hinweise seitens des Finanzamts haben die Gesellschafter der GmbH die Satzungsregelung zur Verm\u00f6gensbindung nicht erg\u00e4nzt. Es kann nur spekuliert werden, warum die Gesellschafter keine entsprechende Satzungs\u00e4nderung durchgef\u00fchrt haben.<\/p>\n\n\n\n<p>Um Streitigkeiten mit dem Finanzamt zu vermeiden, sollten sich NPOs bei der Gestaltung ihrer Satzung an dem Wortlaut der <strong><a href=\"https:\/\/winheller.com\/blog\/was-ist-die-mustersatzung\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mustersatzung<\/a><\/strong> orientieren und nur in begr\u00fcndeten Ausnahmef\u00e4llen davon abweichen. Unsere erfahrenen Anw\u00e4lte stehen Ihnen bei der rechtssicheren Gestaltung Ihrer Satzung gerne zur Seite.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.google.com\/search?q=BFH+Urteil+26.08.2021+V+R+11%2F20\">BFH, Urteil v. 26.08.2021 \u2013 V R 11\/20<\/a><\/p>\n\n\n\n<p>Weiterlesen:<br><strong><a href=\"https:\/\/winheller.com\/blog\/mustersatzung-wortlaut-verbindlich\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mustersatzung in gemeinn\u00fctzigen Organisationen: Ist der Wortlaut verbindlich?<br><\/a><a href=\"https:\/\/www.winheller.com\/gemeinnuetzigkeitsrecht\/satzungsgestaltung.html\" target=\"_blank\" rel=\"noreferrer noopener\">Rechtssichere Gestaltung der Satzung Ihres Vereins oder Verbands<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Satzung ist das Herzst\u00fcck einer gemeinn\u00fctzigen Organisation. \u00dcber ihre Gestaltung kann so mancher Streit innerhalb der eigenen Reihen, aber auch mit den Beh\u00f6rden wie zum Beispiel dem Finanzamt entstehen. Wie wichtig eine gute Satzungsgestaltung ist, zeigt j\u00fcngst ein Urteil des [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":9918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1900,60],"tags":[],"class_list":["post-16220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aberkennung-gemeinnuetzigkeit","category-ggmbh-recht"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/16220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/comments?post=16220"}],"version-history":[{"count":13,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/16220\/revisions"}],"predecessor-version":[{"id":16281,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/posts\/16220\/revisions\/16281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/media\/9918"}],"wp:attachment":[{"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/media?parent=16220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/categories?post=16220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/winheller.com\/blog\/wp-json\/wp\/v2\/tags?post=16220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}